{"id":6975,"date":"2025-06-23T20:25:18","date_gmt":"2025-06-23T20:25:18","guid":{"rendered":"https:\/\/www.equalmedia.mx\/site\/?p=6975"},"modified":"2025-06-24T03:23:36","modified_gmt":"2025-06-24T03:23:36","slug":"la-joya-del-indie-rock-argentino-las-ligas-menores-esta-de-regreso-con-el-anuncio-de-nuevo-album-y-fechas-por-mexico","status":"publish","type":"post","link":"https:\/\/www.equalmedia.mx\/site\/concertos\/la-joya-del-indie-rock-argentino-las-ligas-menores-esta-de-regreso-con-el-anuncio-de-nuevo-album-y-fechas-por-mexico\/","title":{"rendered":"La joya del indie rock argentino, Las Ligas Menores, est\u00e1 de regreso con el anuncio de nuevo \u00e1lbum y fechas por M\u00e9xico."},"content":{"rendered":"\n<p>\u00a1Por fin se hacen presentas las esperadas noticias sobre&nbsp;la tercera entrega de larga duraci\u00f3n de la querida banda argentina,&nbsp;<strong>Las Ligas Menores<\/strong>!<\/p>\n\n\n\n<p>Presentando la imagen de este LP que se estren\u00f3 este pasado viernes 20 de junio en todas las plataformas,\u00a0<strong><em>A Esta Altura<\/em><\/strong>\u00a0llega como uno de los materiales m\u00e1s esperados del a\u00f1o en la comunidad musical independiente de Latinoam\u00e9rica.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/06\/373b0014-5b76-cbf6-34be-bdf7e7db594c.jpg\" alt=\"\" class=\"wp-image-6978\" width=\"468\" height=\"494\" srcset=\"https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/06\/373b0014-5b76-cbf6-34be-bdf7e7db594c.jpg 800w, https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/06\/373b0014-5b76-cbf6-34be-bdf7e7db594c-284x300.jpg 284w, https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/06\/373b0014-5b76-cbf6-34be-bdf7e7db594c-768x810.jpg 768w, https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/06\/373b0014-5b76-cbf6-34be-bdf7e7db594c-300x317.jpg 300w, https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/06\/373b0014-5b76-cbf6-34be-bdf7e7db594c-600x633.jpg 600w\" sizes=\"(max-width: 468px) 100vw, 468px\" \/><\/figure>\n<\/div>\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong><em>A Esta Altura<\/em><\/strong>&nbsp;es la banda sonora de una ruta que viaja de la ciudad hacia la estepa, iniciando al atardecer y con toda la noche de frente. Usa la desilusi\u00f3n como combustible para alejarse de todo lo que hace mal y abrigarse en lo sonoro. Con poes\u00eda directa y direcci\u00f3n clara el nuevo \u00e1lbum de&nbsp;<strong>Las Ligas Menores<\/strong>&nbsp;desarma las expectativas rompiendo con toda frontera estil\u00edstica. Se sumerge en una lluvia de distorsiones, sensibilidad, arreglos surrealistas y fuerza r\u00edtmica con el foco puesto en develar un viaje sonoro.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><a href=\"https:\/\/ascendente.us21.list-manage.com\/track\/click?u=4215a6daffd7ad51ff7903541&amp;id=e81d2db476&amp;e=220c79cd91\" target=\"_blank\" rel=\"noreferrer noopener\">\u00a1Esc\u00fachalo ahora!<\/a><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p><strong>Las Ligas Menores<\/strong><\/p>\n\n\n\n<p><strong>Las Ligas Menores<\/strong>&nbsp;lograron consolidarse como uno de los grupos argentinos con mayor proyecci\u00f3n en Latinoamerica y Espa\u00f1a. Hoy anticipa su tercer LP y continua su camino a las grandes ligas. Formado en 2011 en la Ciudad de Buenos Aires, el grupo lleva publicados dos larga duraci\u00f3n: el hom\u00f3nimo&nbsp;<strong><em>Las Ligas Menores<\/em><\/strong>&nbsp;(2014) y&nbsp;<strong><em>Fuego Artificial<\/em><\/strong>&nbsp;(2018) as\u00ed&nbsp;como&nbsp;sucesivos simples y el descatalogado (y ya de culto) EP debut&nbsp;<strong><em>El Disco Suplente<\/em><\/strong>&nbsp;(2012). Desde sus comienzos Las Ligas Menores tocaron en las principales ciudades de Argentina y Latinoam\u00e9rica -Uruguay, Chile, Peru, Paraguay, Colombia, Costa Rica, Guatemala, El Salvador y tres giras por M\u00e9xico-, realizaron varias giras par Espa\u00f1a y una serie de recitales en Estados Unidos.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" data-src=\"https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/06\/LIGAS_MX-TOUR_GRAL-FEED_BAJA-819x1024.jpg\" alt=\"\" class=\"wp-image-6980 lazyload\" width=\"508\" height=\"635\" data-srcset=\"https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/06\/LIGAS_MX-TOUR_GRAL-FEED_BAJA-819x1024.jpg 819w, https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/06\/LIGAS_MX-TOUR_GRAL-FEED_BAJA-240x300.jpg 240w, https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/06\/LIGAS_MX-TOUR_GRAL-FEED_BAJA-768x960.jpg 768w, https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/06\/LIGAS_MX-TOUR_GRAL-FEED_BAJA-300x375.jpg 300w, https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/06\/LIGAS_MX-TOUR_GRAL-FEED_BAJA-600x750.jpg 600w, https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/06\/LIGAS_MX-TOUR_GRAL-FEED_BAJA.jpg 1080w\" data-sizes=\"(max-width: 508px) 100vw, 508px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 508px; --smush-placeholder-aspect-ratio: 508\/635;\" \/><\/figure>\n<\/div>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Por fin se hacen presentas las esperadas noticias sobre&nbsp;la tercera entrega de larga duraci\u00f3n de la querida banda argentina,&nbsp;Las Ligas Menores! Presentando la imagen de este LP que se estren\u00f3 este pasado viernes 20 de junio en todas las plataformas,\u00a0A Esta Altura\u00a0llega como uno de los materiales m\u00e1s esperados del a\u00f1o en la comunidad musical [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6976,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[340,544,546,545,547],"class_list":["post-6975","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-concertos","tag-equal-music","tag-las-ligas-menores","tag-las-ligas-menores-argentina","tag-las-ligas-menores-mexico","tag-las-ligas-menores-tour"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Equal Media | Hagamos que Suceda<\/title>\n<meta name=\"description\" content=\"Conectamos el mensaje de tu banda musical con audiencias interesadas en conocerles | Te ayudamos a alcanzar tus objetivos | HAGAMOS QUE SUCEDA\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.equalmedia.mx\/site\/concertos\/la-joya-del-indie-rock-argentino-las-ligas-menores-esta-de-regreso-con-el-anuncio-de-nuevo-album-y-fechas-por-mexico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Equal Media | Hagamos que Suceda\" \/>\n<meta property=\"og:description\" content=\"Conectamos el mensaje de tu banda musical con audiencias interesadas en conocerles | Te ayudamos a alcanzar tus objetivos | HAGAMOS QUE SUCEDA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.equalmedia.mx\/site\/concertos\/la-joya-del-indie-rock-argentino-las-ligas-menores-esta-de-regreso-con-el-anuncio-de-nuevo-album-y-fechas-por-mexico\/\" \/>\n<meta property=\"og:site_name\" content=\"EQUAL MUSIC | Cultura Latina en Movimiento\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-23T20:25:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-24T03:23:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/06\/f60eb731-533f-db43-8154-38383eecdf52.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"796\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equal Media\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equal Media\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.equalmedia.mx\/site\/concertos\/la-joya-del-indie-rock-argentino-las-ligas-menores-esta-de-regreso-con-el-anuncio-de-nuevo-album-y-fechas-por-mexico\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.equalmedia.mx\/site\/concertos\/la-joya-del-indie-rock-argentino-las-ligas-menores-esta-de-regreso-con-el-anuncio-de-nuevo-album-y-fechas-por-mexico\/\"},\"author\":{\"name\":\"Equal Media\",\"@id\":\"https:\/\/www.equalmedia.mx\/site\/#\/schema\/person\/41b6e60d650a80262fa6b5189bbb9f20\"},\"headline\":\"La joya del indie rock argentino, Las Ligas Menores, est\u00e1 de regreso con el anuncio de nuevo \u00e1lbum y fechas por M\u00e9xico.\",\"datePublished\":\"2025-06-23T20:25:18+00:00\",\"dateModified\":\"2025-06-24T03:23:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.equalmedia.mx\/site\/concertos\/la-joya-del-indie-rock-argentino-las-ligas-menores-esta-de-regreso-con-el-anuncio-de-nuevo-album-y-fechas-por-mexico\/\"},\"wordCount\":322,\"publisher\":{\"@id\":\"https:\/\/www.equalmedia.mx\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.equalmedia.mx\/site\/concertos\/la-joya-del-indie-rock-argentino-las-ligas-menores-esta-de-regreso-con-el-anuncio-de-nuevo-album-y-fechas-por-mexico\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/06\/f60eb731-533f-db43-8154-38383eecdf52.jpg\",\"keywords\":[\"Equal Music\",\"Las ligas menores\",\"las ligas menores argentina\",\"las ligas menores mexico\",\"las ligas menores tour\"],\"articleSection\":[\"Conciertos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.equalmedia.mx\/site\/concertos\/la-joya-del-indie-rock-argentino-las-ligas-menores-esta-de-regreso-con-el-anuncio-de-nuevo-album-y-fechas-por-mexico\/\",\"url\":\"https:\/\/www.equalmedia.mx\/site\/concertos\/la-joya-del-indie-rock-argentino-las-ligas-menores-esta-de-regreso-con-el-anuncio-de-nuevo-album-y-fechas-por-mexico\/\",\"name\":\"Equal Media | Hagamos que Suceda\",\"isPartOf\":{\"@id\":\"https:\/\/www.equalmedia.mx\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.equalmedia.mx\/site\/concertos\/la-joya-del-indie-rock-argentino-las-ligas-menores-esta-de-regreso-con-el-anuncio-de-nuevo-album-y-fechas-por-mexico\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.equalmedia.mx\/site\/concertos\/la-joya-del-indie-rock-argentino-las-ligas-menores-esta-de-regreso-con-el-anuncio-de-nuevo-album-y-fechas-por-mexico\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/06\/f60eb731-533f-db43-8154-38383eecdf52.jpg\",\"datePublished\":\"2025-06-23T20:25:18+00:00\",\"dateModified\":\"2025-06-24T03:23:36+00:00\",\"description\":\"Conectamos el mensaje de tu banda musical con audiencias interesadas en conocerles | Te ayudamos a alcanzar tus objetivos | HAGAMOS QUE SUCEDA\",\"breadcrumb\":{\"@id\":\"https:\/\/www.equalmedia.mx\/site\/concertos\/la-joya-del-indie-rock-argentino-las-ligas-menores-esta-de-regreso-con-el-anuncio-de-nuevo-album-y-fechas-por-mexico\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.equalmedia.mx\/site\/concertos\/la-joya-del-indie-rock-argentino-las-ligas-menores-esta-de-regreso-con-el-anuncio-de-nuevo-album-y-fechas-por-mexico\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.equalmedia.mx\/site\/concertos\/la-joya-del-indie-rock-argentino-las-ligas-menores-esta-de-regreso-con-el-anuncio-de-nuevo-album-y-fechas-por-mexico\/#primaryimage\",\"url\":\"https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/06\/f60eb731-533f-db43-8154-38383eecdf52.jpg\",\"contentUrl\":\"https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/06\/f60eb731-533f-db43-8154-38383eecdf52.jpg\",\"width\":1200,\"height\":796},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.equalmedia.mx\/site\/concertos\/la-joya-del-indie-rock-argentino-las-ligas-menores-esta-de-regreso-con-el-anuncio-de-nuevo-album-y-fechas-por-mexico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.equalmedia.mx\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La joya del indie rock argentino, Las Ligas Menores, est\u00e1 de regreso con el anuncio de nuevo \u00e1lbum y fechas por M\u00e9xico.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.equalmedia.mx\/site\/#website\",\"url\":\"https:\/\/www.equalmedia.mx\/site\/\",\"name\":\"EQUAL MUSIC | Cultura Latina en Movimiento\",\"description\":\"Ritmo en movimiento.\",\"publisher\":{\"@id\":\"https:\/\/www.equalmedia.mx\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.equalmedia.mx\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.equalmedia.mx\/site\/#organization\",\"name\":\"EQUAL MUSIC | Cultura Latina en Movimiento\",\"url\":\"https:\/\/www.equalmedia.mx\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.equalmedia.mx\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2021\/07\/logoblanco.png\",\"contentUrl\":\"https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2021\/07\/logoblanco.png\",\"width\":1920,\"height\":589,\"caption\":\"EQUAL MUSIC | Cultura Latina en Movimiento\"},\"image\":{\"@id\":\"https:\/\/www.equalmedia.mx\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.equalmedia.mx\/site\/#\/schema\/person\/41b6e60d650a80262fa6b5189bbb9f20\",\"name\":\"Equal Media\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.equalmedia.mx\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/51c3f8f080f557c61349ab37ab35c9f967b3b271510dd8ef0b9b16a3dd5a89e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/51c3f8f080f557c61349ab37ab35c9f967b3b271510dd8ef0b9b16a3dd5a89e9?s=96&d=mm&r=g\",\"caption\":\"Equal Media\"},\"description\":\"Equal Media es una productora y agencia de estrategia cultural transmedia que impulsa la visibilidad de la m\u00fasica y cultura latina a trav\u00e9s de contenidos originales, multiplataforma y con enfoque social. Con operaci\u00f3n desde Estados Unidos, M\u00e9xico y Colombia, Equal Media se ha consolidado como un actor clave en la narrativa documental, la curadur\u00eda musical y la creaci\u00f3n de formatos de alto impacto para audiencias latinas globales. Sus producciones incluyen Equal Music Sessions \u2014con m\u00e1s de 300 artistas programados en LATV Network\u2014, la serie Hunters y el documental 4TRO EL3MENTOS. Sus contenidos son emitidos en prime time en EE.UU. v\u00eda LATV y VOD, alcanzando m\u00e1s de 62 millones de hogares en mercados como Nueva York, Los \u00c1ngeles, Miami y Chicago. Equal Media ha estado presente con cobertura original y branded content en eventos como el Media Hub de los Latin Grammys, LAMC (NY), BIME (Bilbao, Bogot\u00e1), Vive Latino (CDMX), MIM LATAM, CAMM, entre otros hubs de la industria. Aliada de plataformas como Keychange, Femnoise, We Make Noise y la Municipalidad de Quilicura (Chile), Equal Media promueve una industria m\u00e1s equitativa, programando de forma activa proyectos liderados por mujeres, comunidades LGBTQ+ y sectores vulnerables. Bajo la direcci\u00f3n de Ulises Sanher \u2014reconocido por la UNAM y otras instituciones acad\u00e9micas por su labor cultural\u2014, Equal Media ha contribuido a formar nuevas audiencias desde la educaci\u00f3n, el activismo y la creatividad. Sanher ha sido invitado como speaker en foros como Circulart (COL), FIMPRO (MEX), Canadian Music Week (CAN), FME (CAN), SIM S\u00e3o Paulo (BR), MUPA (PAN), Corriente (PER) y Brasil Trends Conference. Tambi\u00e9n ha sido jurado externo de los Premios Rolling Stone en Espa\u00f1ol en Miami y ha ofrecido asesor\u00eda creativa en colaboraci\u00f3n con Berklee Valencia y la Asociaci\u00f3n de Supervisores Musicales.\",\"sameAs\":[\"https:\/\/www.equalmedia.mx\/\",\"https:\/\/www.instagram.com\/equal.music\",\"https:\/\/www.linkedin.com\/in\/ulises-sanher\/\",\"https:\/\/www.youtube.com\/@equalmusicworld\"],\"url\":\"https:\/\/www.equalmedia.mx\/site\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Equal Media | Hagamos que Suceda","description":"Conectamos el mensaje de tu banda musical con audiencias interesadas en conocerles | Te ayudamos a alcanzar tus objetivos | HAGAMOS QUE SUCEDA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.equalmedia.mx\/site\/concertos\/la-joya-del-indie-rock-argentino-las-ligas-menores-esta-de-regreso-con-el-anuncio-de-nuevo-album-y-fechas-por-mexico\/","og_locale":"es_ES","og_type":"article","og_title":"Equal Media | Hagamos que Suceda","og_description":"Conectamos el mensaje de tu banda musical con audiencias interesadas en conocerles | Te ayudamos a alcanzar tus objetivos | HAGAMOS QUE SUCEDA","og_url":"https:\/\/www.equalmedia.mx\/site\/concertos\/la-joya-del-indie-rock-argentino-las-ligas-menores-esta-de-regreso-con-el-anuncio-de-nuevo-album-y-fechas-por-mexico\/","og_site_name":"EQUAL MUSIC | Cultura Latina en Movimiento","article_published_time":"2025-06-23T20:25:18+00:00","article_modified_time":"2025-06-24T03:23:36+00:00","og_image":[{"width":1200,"height":796,"url":"https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/06\/f60eb731-533f-db43-8154-38383eecdf52.jpg","type":"image\/jpeg"}],"author":"Equal Media","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Equal Media","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.equalmedia.mx\/site\/concertos\/la-joya-del-indie-rock-argentino-las-ligas-menores-esta-de-regreso-con-el-anuncio-de-nuevo-album-y-fechas-por-mexico\/#article","isPartOf":{"@id":"https:\/\/www.equalmedia.mx\/site\/concertos\/la-joya-del-indie-rock-argentino-las-ligas-menores-esta-de-regreso-con-el-anuncio-de-nuevo-album-y-fechas-por-mexico\/"},"author":{"name":"Equal Media","@id":"https:\/\/www.equalmedia.mx\/site\/#\/schema\/person\/41b6e60d650a80262fa6b5189bbb9f20"},"headline":"La joya del indie rock argentino, Las Ligas Menores, est\u00e1 de regreso con el anuncio de nuevo \u00e1lbum y fechas por M\u00e9xico.","datePublished":"2025-06-23T20:25:18+00:00","dateModified":"2025-06-24T03:23:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.equalmedia.mx\/site\/concertos\/la-joya-del-indie-rock-argentino-las-ligas-menores-esta-de-regreso-con-el-anuncio-de-nuevo-album-y-fechas-por-mexico\/"},"wordCount":322,"publisher":{"@id":"https:\/\/www.equalmedia.mx\/site\/#organization"},"image":{"@id":"https:\/\/www.equalmedia.mx\/site\/concertos\/la-joya-del-indie-rock-argentino-las-ligas-menores-esta-de-regreso-con-el-anuncio-de-nuevo-album-y-fechas-por-mexico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/06\/f60eb731-533f-db43-8154-38383eecdf52.jpg","keywords":["Equal Music","Las ligas menores","las ligas menores argentina","las ligas menores mexico","las ligas menores tour"],"articleSection":["Conciertos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.equalmedia.mx\/site\/concertos\/la-joya-del-indie-rock-argentino-las-ligas-menores-esta-de-regreso-con-el-anuncio-de-nuevo-album-y-fechas-por-mexico\/","url":"https:\/\/www.equalmedia.mx\/site\/concertos\/la-joya-del-indie-rock-argentino-las-ligas-menores-esta-de-regreso-con-el-anuncio-de-nuevo-album-y-fechas-por-mexico\/","name":"Equal Media | Hagamos que Suceda","isPartOf":{"@id":"https:\/\/www.equalmedia.mx\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.equalmedia.mx\/site\/concertos\/la-joya-del-indie-rock-argentino-las-ligas-menores-esta-de-regreso-con-el-anuncio-de-nuevo-album-y-fechas-por-mexico\/#primaryimage"},"image":{"@id":"https:\/\/www.equalmedia.mx\/site\/concertos\/la-joya-del-indie-rock-argentino-las-ligas-menores-esta-de-regreso-con-el-anuncio-de-nuevo-album-y-fechas-por-mexico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/06\/f60eb731-533f-db43-8154-38383eecdf52.jpg","datePublished":"2025-06-23T20:25:18+00:00","dateModified":"2025-06-24T03:23:36+00:00","description":"Conectamos el mensaje de tu banda musical con audiencias interesadas en conocerles | Te ayudamos a alcanzar tus objetivos | HAGAMOS QUE SUCEDA","breadcrumb":{"@id":"https:\/\/www.equalmedia.mx\/site\/concertos\/la-joya-del-indie-rock-argentino-las-ligas-menores-esta-de-regreso-con-el-anuncio-de-nuevo-album-y-fechas-por-mexico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.equalmedia.mx\/site\/concertos\/la-joya-del-indie-rock-argentino-las-ligas-menores-esta-de-regreso-con-el-anuncio-de-nuevo-album-y-fechas-por-mexico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.equalmedia.mx\/site\/concertos\/la-joya-del-indie-rock-argentino-las-ligas-menores-esta-de-regreso-con-el-anuncio-de-nuevo-album-y-fechas-por-mexico\/#primaryimage","url":"https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/06\/f60eb731-533f-db43-8154-38383eecdf52.jpg","contentUrl":"https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/06\/f60eb731-533f-db43-8154-38383eecdf52.jpg","width":1200,"height":796},{"@type":"BreadcrumbList","@id":"https:\/\/www.equalmedia.mx\/site\/concertos\/la-joya-del-indie-rock-argentino-las-ligas-menores-esta-de-regreso-con-el-anuncio-de-nuevo-album-y-fechas-por-mexico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.equalmedia.mx\/site\/"},{"@type":"ListItem","position":2,"name":"La joya del indie rock argentino, Las Ligas Menores, est\u00e1 de regreso con el anuncio de nuevo \u00e1lbum y fechas por M\u00e9xico."}]},{"@type":"WebSite","@id":"https:\/\/www.equalmedia.mx\/site\/#website","url":"https:\/\/www.equalmedia.mx\/site\/","name":"EQUAL MUSIC | Cultura Latina en Movimiento","description":"Ritmo en movimiento.","publisher":{"@id":"https:\/\/www.equalmedia.mx\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.equalmedia.mx\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.equalmedia.mx\/site\/#organization","name":"EQUAL MUSIC | Cultura Latina en Movimiento","url":"https:\/\/www.equalmedia.mx\/site\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.equalmedia.mx\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2021\/07\/logoblanco.png","contentUrl":"https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2021\/07\/logoblanco.png","width":1920,"height":589,"caption":"EQUAL MUSIC | Cultura Latina en Movimiento"},"image":{"@id":"https:\/\/www.equalmedia.mx\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.equalmedia.mx\/site\/#\/schema\/person\/41b6e60d650a80262fa6b5189bbb9f20","name":"Equal Media","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.equalmedia.mx\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/51c3f8f080f557c61349ab37ab35c9f967b3b271510dd8ef0b9b16a3dd5a89e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/51c3f8f080f557c61349ab37ab35c9f967b3b271510dd8ef0b9b16a3dd5a89e9?s=96&d=mm&r=g","caption":"Equal Media"},"description":"Equal Media es una productora y agencia de estrategia cultural transmedia que impulsa la visibilidad de la m\u00fasica y cultura latina a trav\u00e9s de contenidos originales, multiplataforma y con enfoque social. Con operaci\u00f3n desde Estados Unidos, M\u00e9xico y Colombia, Equal Media se ha consolidado como un actor clave en la narrativa documental, la curadur\u00eda musical y la creaci\u00f3n de formatos de alto impacto para audiencias latinas globales. Sus producciones incluyen Equal Music Sessions \u2014con m\u00e1s de 300 artistas programados en LATV Network\u2014, la serie Hunters y el documental 4TRO EL3MENTOS. Sus contenidos son emitidos en prime time en EE.UU. v\u00eda LATV y VOD, alcanzando m\u00e1s de 62 millones de hogares en mercados como Nueva York, Los \u00c1ngeles, Miami y Chicago. Equal Media ha estado presente con cobertura original y branded content en eventos como el Media Hub de los Latin Grammys, LAMC (NY), BIME (Bilbao, Bogot\u00e1), Vive Latino (CDMX), MIM LATAM, CAMM, entre otros hubs de la industria. Aliada de plataformas como Keychange, Femnoise, We Make Noise y la Municipalidad de Quilicura (Chile), Equal Media promueve una industria m\u00e1s equitativa, programando de forma activa proyectos liderados por mujeres, comunidades LGBTQ+ y sectores vulnerables. Bajo la direcci\u00f3n de Ulises Sanher \u2014reconocido por la UNAM y otras instituciones acad\u00e9micas por su labor cultural\u2014, Equal Media ha contribuido a formar nuevas audiencias desde la educaci\u00f3n, el activismo y la creatividad. Sanher ha sido invitado como speaker en foros como Circulart (COL), FIMPRO (MEX), Canadian Music Week (CAN), FME (CAN), SIM S\u00e3o Paulo (BR), MUPA (PAN), Corriente (PER) y Brasil Trends Conference. Tambi\u00e9n ha sido jurado externo de los Premios Rolling Stone en Espa\u00f1ol en Miami y ha ofrecido asesor\u00eda creativa en colaboraci\u00f3n con Berklee Valencia y la Asociaci\u00f3n de Supervisores Musicales.","sameAs":["https:\/\/www.equalmedia.mx\/","https:\/\/www.instagram.com\/equal.music","https:\/\/www.linkedin.com\/in\/ulises-sanher\/","https:\/\/www.youtube.com\/@equalmusicworld"],"url":"https:\/\/www.equalmedia.mx\/site\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.equalmedia.mx\/site\/wp-json\/wp\/v2\/posts\/6975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.equalmedia.mx\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.equalmedia.mx\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.equalmedia.mx\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.equalmedia.mx\/site\/wp-json\/wp\/v2\/comments?post=6975"}],"version-history":[{"count":4,"href":"https:\/\/www.equalmedia.mx\/site\/wp-json\/wp\/v2\/posts\/6975\/revisions"}],"predecessor-version":[{"id":6984,"href":"https:\/\/www.equalmedia.mx\/site\/wp-json\/wp\/v2\/posts\/6975\/revisions\/6984"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.equalmedia.mx\/site\/wp-json\/wp\/v2\/media\/6976"}],"wp:attachment":[{"href":"https:\/\/www.equalmedia.mx\/site\/wp-json\/wp\/v2\/media?parent=6975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.equalmedia.mx\/site\/wp-json\/wp\/v2\/categories?post=6975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.equalmedia.mx\/site\/wp-json\/wp\/v2\/tags?post=6975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}