{"id":7398,"date":"2025-08-29T02:40:42","date_gmt":"2025-08-29T02:40:42","guid":{"rendered":"https:\/\/www.equalmedia.mx\/site\/?p=7398"},"modified":"2025-08-29T02:40:42","modified_gmt":"2025-08-29T02:40:42","slug":"sofi-mayen-normal-album-alt-pop-2025","status":"publish","type":"post","link":"https:\/\/www.equalmedia.mx\/site\/radar\/sofi-mayen-normal-album-alt-pop-2025\/","title":{"rendered":"Sofi Mayen convierte lo cotidiano en arte confesional con Normal"},"content":{"rendered":"\n<p><strong>Por Ulises Sanher<\/strong><\/p>\n\n\n\n<p>Hay discos que se sienten como testigos. No exigen, no empujan: simplemente caminan contigo. <em>Normal<\/em>, el nuevo trabajo de <strong>Sofi Mayen<\/strong>, es uno de esos discos. Desde su primer track <em>\u201cPreg\u00fantamelo a m\u00ed\u201d<\/em>, queda claro que estamos ante una obra pensada para acompa\u00f1ar los d\u00edas dif\u00edciles, las noches largas y, sobre todo, los procesos emocionales que no caben en palabras, pero s\u00ed en canciones.<\/p>\n\n\n\n<p>Producido en complicidad con <strong>Manu Jalil<\/strong> \u2014cuya sensibilidad sonora se entrelaza de forma perfecta con la l\u00edrica de Sofi\u2014, este \u00e1lbum tiene el tacto de una conversaci\u00f3n sincera entre amigos que se entienden sin explicarse. No hay dramatismo forzado, no hay grandes declaraciones: hay poes\u00eda real, tejida con melod\u00edas suaves, texturas emocionales y una entrega vocal que te mira a los ojos.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"\ud835\udde6\ud835\uddfc\ud835\uddf3\ud835\uddf6 \ud835\udde0\ud835\uddee\ud835\ude06\ud835\uddf2\ud835\uddfb | \ud835\uddd8\ud835\uddfb\ud835\ude01\ud835\uddff\ud835\uddf2\ud835\ude03\ud835\uddf6\ud835\ude00\ud835\ude01\ud835\uddee\" width=\"1300\" height=\"731\" data-src=\"https:\/\/www.youtube.com\/embed\/T1RZbrSO_lY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe>\n<\/div><figcaption class=\"wp-element-caption\"><em>Entrevista Sofi Mayen-Equal Music\/ Cortes\u00eda The Music Joint<\/em><\/figcaption><\/figure>\n\n\n\n<p><em>\u201cEntre Tus Pies\u201d<\/em>, una de las piezas clave del disco, es la ilustraci\u00f3n de c\u00f3mo una relaci\u00f3n puede construirse con asimetr\u00eda emocional. La letra no busca culpas ni se\u00f1ala responsables; solo dibuja, con delicadeza, c\u00f3mo uno puede dar m\u00e1s sin esperar tanto a cambio. La producci\u00f3n respeta ese tono \u00edntimo, casi como si estuvi\u00e9ramos leyendo una carta privada. Y as\u00ed, sin levantar la voz, la canci\u00f3n nos desarma.<\/p>\n\n\n\n<p>En <em>\u201cAparentemente\u201d<\/em>, el viaje llega a uno de sus momentos m\u00e1s introspectivos. Es un soliloquio mental, una conversaci\u00f3n consigo misma en la que Sofi reconoce, acepta y se prepara para soltar. Esta pieza no solo marca el punto de inflexi\u00f3n emocional del \u00e1lbum, sino que evidencia una madurez compositiva que, sin necesidad de adornos, se instala con fuerza en el coraz\u00f3n del oyente.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/08\/Sofi-Mayen-NORMAL-2025-2-683x1024.jpg\" alt=\"\" class=\"wp-image-7400\" width=\"346\" height=\"518\" srcset=\"https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/08\/Sofi-Mayen-NORMAL-2025-2-683x1024.jpg 683w, https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/08\/Sofi-Mayen-NORMAL-2025-2-200x300.jpg 200w, https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/08\/Sofi-Mayen-NORMAL-2025-2-768x1152.jpg 768w, https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/08\/Sofi-Mayen-NORMAL-2025-2-1024x1536.jpg 1024w, https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/08\/Sofi-Mayen-NORMAL-2025-2-1365x2048.jpg 1365w, https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/08\/Sofi-Mayen-NORMAL-2025-2-300x450.jpg 300w, https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/08\/Sofi-Mayen-NORMAL-2025-2-600x900.jpg 600w, https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/08\/Sofi-Mayen-NORMAL-2025-2-scaled.jpg 1707w\" sizes=\"(max-width: 346px) 100vw, 346px\" \/><figcaption class=\"wp-element-caption\"><em>Sofi Mayen \/ Cortes\u00eda The Music Joint<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<p>El single <em>\u201cMe Estoy Cansando de Ti\u201d<\/em> funciona como una confrontaci\u00f3n personal frente al espejo: una canci\u00f3n que no habla solo del otro, sino del momento exacto en el que nos preguntamos cu\u00e1ndo nos perdimos. Es un tema que resume con claridad la esencia de <em>Normal<\/em>: explorar las fisuras cotidianas que muchas veces evitamos mirar de frente.<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Sofi Mayen - Me estoy cansando de ti\" width=\"1300\" height=\"731\" data-src=\"https:\/\/www.youtube.com\/embed\/r06VAk-q5lQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Cada canci\u00f3n de <em>Normal<\/em> parece ocupar un cap\u00edtulo en una novela emocional, donde las historias de amor, dependencia, duelo, resignaci\u00f3n y renacimiento se tejen con crudeza y belleza. Lo que hace especial a este disco es que no busca ser perfecto; busca ser real. Y lo logra con creces.<\/p>\n\n\n\n<p>M\u00e1s all\u00e1 de su belleza t\u00e9cnica o de su estructura narrativa precisa, <em>Normal<\/em> tiene algo que pocos discos consiguen: se vuelve compa\u00f1\u00eda. Es ese tipo de \u00e1lbum que puedes escuchar solo, caminando por la ciudad, o en casa, con una taza de t\u00e9 en la mano, sabiendo que cada verso es un espejo.<\/p>\n\n\n\n<p>Se le augura \u00e9xito no solo por la calidad de su producci\u00f3n, sino por una verdad que siempre se impone: los discos escritos con las entra\u00f1as conectan de inmediato. Y cuando hay verdad, cuando hay entra\u00f1a, hay permanencia.<\/p>\n\n\n\n<p>Sofi Mayen no solo escribi\u00f3 un gran disco de alt\u2011pop. Escribi\u00f3 una obra que le habla de t\u00fa a t\u00fa a una generaci\u00f3n que busca respuestas en lo \u00edntimo, en lo visceral, en lo que no se ve pero se siente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Ulises Sanher Hay discos que se sienten como testigos. No exigen, no empujan: simplemente caminan contigo. Normal, el nuevo trabajo de Sofi Mayen, es uno de esos discos. Desde su primer track \u201cPreg\u00fantamelo a m\u00ed\u201d, queda claro que estamos ante una obra pensada para acompa\u00f1ar los d\u00edas dif\u00edciles, las noches largas y, sobre todo, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7399,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1252],"tags":[1527,1520,1528,1525,1395,496,1524,1519,922,1526,1523,1522,440,913,1133,1521],"class_list":["post-7398","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-radar","tag-albumes-confesionales","tag-alt-pop","tag-amor-propio","tag-artistas-mexicanas","tag-discos-2025","tag-equal-media","tag-indie-pop","tag-manu-jalil","tag-musica-emocional","tag-musica-honesta","tag-musica-mexicana","tag-normal","tag-nuevo-disco","tag-pop-alternativo","tag-pop-latino","tag-sofi-mayen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Normal, el disco m\u00e1s \u00edntimo de Sofi Mayen, es una carta abierta al amor propio<\/title>\n<meta name=\"description\" content=\"Sofi Mayen lanza Normal, un \u00e1lbum de alt-pop escrito con las entra\u00f1as. Producido por Manu Jalil, este disco es un recorrido emocional que habla del amor, el duelo y la reconstrucci\u00f3n personal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.equalmedia.mx\/site\/radar\/sofi-mayen-normal-album-alt-pop-2025\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Normal, el disco m\u00e1s \u00edntimo de Sofi Mayen, es una carta abierta al amor propio\" \/>\n<meta property=\"og:description\" content=\"Sofi Mayen lanza Normal, un \u00e1lbum de alt-pop escrito con las entra\u00f1as. Producido por Manu Jalil, este disco es un recorrido emocional que habla del amor, el duelo y la reconstrucci\u00f3n personal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.equalmedia.mx\/site\/radar\/sofi-mayen-normal-album-alt-pop-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"EQUAL MUSIC | Cultura Latina en Movimiento\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-29T02:40:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/08\/Sofi-Mayen-NORMAL-2025-4-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equal Media\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equal Media\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.equalmedia.mx\/site\/radar\/sofi-mayen-normal-album-alt-pop-2025\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.equalmedia.mx\/site\/radar\/sofi-mayen-normal-album-alt-pop-2025\/\"},\"author\":{\"name\":\"Equal Media\",\"@id\":\"https:\/\/www.equalmedia.mx\/site\/#\/schema\/person\/41b6e60d650a80262fa6b5189bbb9f20\"},\"headline\":\"Sofi Mayen convierte lo cotidiano en arte confesional con Normal\",\"datePublished\":\"2025-08-29T02:40:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.equalmedia.mx\/site\/radar\/sofi-mayen-normal-album-alt-pop-2025\/\"},\"wordCount\":586,\"publisher\":{\"@id\":\"https:\/\/www.equalmedia.mx\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.equalmedia.mx\/site\/radar\/sofi-mayen-normal-album-alt-pop-2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/08\/Sofi-Mayen-NORMAL-2025-4-scaled.jpg\",\"keywords\":[\"\u00e1lbumes confesionales\",\"alt-pop\",\"amor propio\",\"artistas mexicanas\",\"discos 2025\",\"equal media\",\"indie pop\",\"Manu Jalil\",\"m\u00fasica emocional\",\"m\u00fasica honesta\",\"m\u00fasica mexicana\",\"Normal\",\"nuevo disco\",\"pop alternativo\",\"pop latino\",\"Sofi Mayen\"],\"articleSection\":[\"Radar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.equalmedia.mx\/site\/radar\/sofi-mayen-normal-album-alt-pop-2025\/\",\"url\":\"https:\/\/www.equalmedia.mx\/site\/radar\/sofi-mayen-normal-album-alt-pop-2025\/\",\"name\":\"Normal, el disco m\u00e1s \u00edntimo de Sofi Mayen, es una carta abierta al amor propio\",\"isPartOf\":{\"@id\":\"https:\/\/www.equalmedia.mx\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.equalmedia.mx\/site\/radar\/sofi-mayen-normal-album-alt-pop-2025\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.equalmedia.mx\/site\/radar\/sofi-mayen-normal-album-alt-pop-2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/08\/Sofi-Mayen-NORMAL-2025-4-scaled.jpg\",\"datePublished\":\"2025-08-29T02:40:42+00:00\",\"description\":\"Sofi Mayen lanza Normal, un \u00e1lbum de alt-pop escrito con las entra\u00f1as. Producido por Manu Jalil, este disco es un recorrido emocional que habla del amor, el duelo y la reconstrucci\u00f3n personal.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.equalmedia.mx\/site\/radar\/sofi-mayen-normal-album-alt-pop-2025\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.equalmedia.mx\/site\/radar\/sofi-mayen-normal-album-alt-pop-2025\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.equalmedia.mx\/site\/radar\/sofi-mayen-normal-album-alt-pop-2025\/#primaryimage\",\"url\":\"https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/08\/Sofi-Mayen-NORMAL-2025-4-scaled.jpg\",\"contentUrl\":\"https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/08\/Sofi-Mayen-NORMAL-2025-4-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.equalmedia.mx\/site\/radar\/sofi-mayen-normal-album-alt-pop-2025\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.equalmedia.mx\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sofi Mayen convierte lo cotidiano en arte confesional con Normal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.equalmedia.mx\/site\/#website\",\"url\":\"https:\/\/www.equalmedia.mx\/site\/\",\"name\":\"EQUAL MUSIC | Cultura Latina en Movimiento\",\"description\":\"Ritmo en movimiento.\",\"publisher\":{\"@id\":\"https:\/\/www.equalmedia.mx\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.equalmedia.mx\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.equalmedia.mx\/site\/#organization\",\"name\":\"EQUAL MUSIC | Cultura Latina en Movimiento\",\"url\":\"https:\/\/www.equalmedia.mx\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.equalmedia.mx\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2021\/07\/logoblanco.png\",\"contentUrl\":\"https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2021\/07\/logoblanco.png\",\"width\":1920,\"height\":589,\"caption\":\"EQUAL MUSIC | Cultura Latina en Movimiento\"},\"image\":{\"@id\":\"https:\/\/www.equalmedia.mx\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.equalmedia.mx\/site\/#\/schema\/person\/41b6e60d650a80262fa6b5189bbb9f20\",\"name\":\"Equal Media\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.equalmedia.mx\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/51c3f8f080f557c61349ab37ab35c9f967b3b271510dd8ef0b9b16a3dd5a89e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/51c3f8f080f557c61349ab37ab35c9f967b3b271510dd8ef0b9b16a3dd5a89e9?s=96&d=mm&r=g\",\"caption\":\"Equal Media\"},\"description\":\"Equal Media es una productora y agencia de estrategia cultural transmedia que impulsa la visibilidad de la m\u00fasica y cultura latina a trav\u00e9s de contenidos originales, multiplataforma y con enfoque social. Con operaci\u00f3n desde Estados Unidos, M\u00e9xico y Colombia, Equal Media se ha consolidado como un actor clave en la narrativa documental, la curadur\u00eda musical y la creaci\u00f3n de formatos de alto impacto para audiencias latinas globales. Sus producciones incluyen Equal Music Sessions \u2014con m\u00e1s de 300 artistas programados en LATV Network\u2014, la serie Hunters y el documental 4TRO EL3MENTOS. Sus contenidos son emitidos en prime time en EE.UU. v\u00eda LATV y VOD, alcanzando m\u00e1s de 62 millones de hogares en mercados como Nueva York, Los \u00c1ngeles, Miami y Chicago. Equal Media ha estado presente con cobertura original y branded content en eventos como el Media Hub de los Latin Grammys, LAMC (NY), BIME (Bilbao, Bogot\u00e1), Vive Latino (CDMX), MIM LATAM, CAMM, entre otros hubs de la industria. Aliada de plataformas como Keychange, Femnoise, We Make Noise y la Municipalidad de Quilicura (Chile), Equal Media promueve una industria m\u00e1s equitativa, programando de forma activa proyectos liderados por mujeres, comunidades LGBTQ+ y sectores vulnerables. Bajo la direcci\u00f3n de Ulises Sanher \u2014reconocido por la UNAM y otras instituciones acad\u00e9micas por su labor cultural\u2014, Equal Media ha contribuido a formar nuevas audiencias desde la educaci\u00f3n, el activismo y la creatividad. Sanher ha sido invitado como speaker en foros como Circulart (COL), FIMPRO (MEX), Canadian Music Week (CAN), FME (CAN), SIM S\u00e3o Paulo (BR), MUPA (PAN), Corriente (PER) y Brasil Trends Conference. Tambi\u00e9n ha sido jurado externo de los Premios Rolling Stone en Espa\u00f1ol en Miami y ha ofrecido asesor\u00eda creativa en colaboraci\u00f3n con Berklee Valencia y la Asociaci\u00f3n de Supervisores Musicales.\",\"sameAs\":[\"https:\/\/www.equalmedia.mx\/\",\"https:\/\/www.instagram.com\/equal.music\",\"https:\/\/www.linkedin.com\/in\/ulises-sanher\/\",\"https:\/\/www.youtube.com\/@equalmusicworld\"],\"url\":\"https:\/\/www.equalmedia.mx\/site\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Normal, el disco m\u00e1s \u00edntimo de Sofi Mayen, es una carta abierta al amor propio","description":"Sofi Mayen lanza Normal, un \u00e1lbum de alt-pop escrito con las entra\u00f1as. Producido por Manu Jalil, este disco es un recorrido emocional que habla del amor, el duelo y la reconstrucci\u00f3n personal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.equalmedia.mx\/site\/radar\/sofi-mayen-normal-album-alt-pop-2025\/","og_locale":"es_ES","og_type":"article","og_title":"Normal, el disco m\u00e1s \u00edntimo de Sofi Mayen, es una carta abierta al amor propio","og_description":"Sofi Mayen lanza Normal, un \u00e1lbum de alt-pop escrito con las entra\u00f1as. Producido por Manu Jalil, este disco es un recorrido emocional que habla del amor, el duelo y la reconstrucci\u00f3n personal.","og_url":"https:\/\/www.equalmedia.mx\/site\/radar\/sofi-mayen-normal-album-alt-pop-2025\/","og_site_name":"EQUAL MUSIC | Cultura Latina en Movimiento","article_published_time":"2025-08-29T02:40:42+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/08\/Sofi-Mayen-NORMAL-2025-4-scaled.jpg","type":"image\/jpeg"}],"author":"Equal Media","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Equal Media","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.equalmedia.mx\/site\/radar\/sofi-mayen-normal-album-alt-pop-2025\/#article","isPartOf":{"@id":"https:\/\/www.equalmedia.mx\/site\/radar\/sofi-mayen-normal-album-alt-pop-2025\/"},"author":{"name":"Equal Media","@id":"https:\/\/www.equalmedia.mx\/site\/#\/schema\/person\/41b6e60d650a80262fa6b5189bbb9f20"},"headline":"Sofi Mayen convierte lo cotidiano en arte confesional con Normal","datePublished":"2025-08-29T02:40:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.equalmedia.mx\/site\/radar\/sofi-mayen-normal-album-alt-pop-2025\/"},"wordCount":586,"publisher":{"@id":"https:\/\/www.equalmedia.mx\/site\/#organization"},"image":{"@id":"https:\/\/www.equalmedia.mx\/site\/radar\/sofi-mayen-normal-album-alt-pop-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/08\/Sofi-Mayen-NORMAL-2025-4-scaled.jpg","keywords":["\u00e1lbumes confesionales","alt-pop","amor propio","artistas mexicanas","discos 2025","equal media","indie pop","Manu Jalil","m\u00fasica emocional","m\u00fasica honesta","m\u00fasica mexicana","Normal","nuevo disco","pop alternativo","pop latino","Sofi Mayen"],"articleSection":["Radar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.equalmedia.mx\/site\/radar\/sofi-mayen-normal-album-alt-pop-2025\/","url":"https:\/\/www.equalmedia.mx\/site\/radar\/sofi-mayen-normal-album-alt-pop-2025\/","name":"Normal, el disco m\u00e1s \u00edntimo de Sofi Mayen, es una carta abierta al amor propio","isPartOf":{"@id":"https:\/\/www.equalmedia.mx\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.equalmedia.mx\/site\/radar\/sofi-mayen-normal-album-alt-pop-2025\/#primaryimage"},"image":{"@id":"https:\/\/www.equalmedia.mx\/site\/radar\/sofi-mayen-normal-album-alt-pop-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/08\/Sofi-Mayen-NORMAL-2025-4-scaled.jpg","datePublished":"2025-08-29T02:40:42+00:00","description":"Sofi Mayen lanza Normal, un \u00e1lbum de alt-pop escrito con las entra\u00f1as. Producido por Manu Jalil, este disco es un recorrido emocional que habla del amor, el duelo y la reconstrucci\u00f3n personal.","breadcrumb":{"@id":"https:\/\/www.equalmedia.mx\/site\/radar\/sofi-mayen-normal-album-alt-pop-2025\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.equalmedia.mx\/site\/radar\/sofi-mayen-normal-album-alt-pop-2025\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.equalmedia.mx\/site\/radar\/sofi-mayen-normal-album-alt-pop-2025\/#primaryimage","url":"https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/08\/Sofi-Mayen-NORMAL-2025-4-scaled.jpg","contentUrl":"https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2025\/08\/Sofi-Mayen-NORMAL-2025-4-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/www.equalmedia.mx\/site\/radar\/sofi-mayen-normal-album-alt-pop-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.equalmedia.mx\/site\/"},{"@type":"ListItem","position":2,"name":"Sofi Mayen convierte lo cotidiano en arte confesional con Normal"}]},{"@type":"WebSite","@id":"https:\/\/www.equalmedia.mx\/site\/#website","url":"https:\/\/www.equalmedia.mx\/site\/","name":"EQUAL MUSIC | Cultura Latina en Movimiento","description":"Ritmo en movimiento.","publisher":{"@id":"https:\/\/www.equalmedia.mx\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.equalmedia.mx\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.equalmedia.mx\/site\/#organization","name":"EQUAL MUSIC | Cultura Latina en Movimiento","url":"https:\/\/www.equalmedia.mx\/site\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.equalmedia.mx\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2021\/07\/logoblanco.png","contentUrl":"https:\/\/www.equalmedia.mx\/site\/wp-content\/uploads\/2021\/07\/logoblanco.png","width":1920,"height":589,"caption":"EQUAL MUSIC | Cultura Latina en Movimiento"},"image":{"@id":"https:\/\/www.equalmedia.mx\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.equalmedia.mx\/site\/#\/schema\/person\/41b6e60d650a80262fa6b5189bbb9f20","name":"Equal Media","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.equalmedia.mx\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/51c3f8f080f557c61349ab37ab35c9f967b3b271510dd8ef0b9b16a3dd5a89e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/51c3f8f080f557c61349ab37ab35c9f967b3b271510dd8ef0b9b16a3dd5a89e9?s=96&d=mm&r=g","caption":"Equal Media"},"description":"Equal Media es una productora y agencia de estrategia cultural transmedia que impulsa la visibilidad de la m\u00fasica y cultura latina a trav\u00e9s de contenidos originales, multiplataforma y con enfoque social. Con operaci\u00f3n desde Estados Unidos, M\u00e9xico y Colombia, Equal Media se ha consolidado como un actor clave en la narrativa documental, la curadur\u00eda musical y la creaci\u00f3n de formatos de alto impacto para audiencias latinas globales. Sus producciones incluyen Equal Music Sessions \u2014con m\u00e1s de 300 artistas programados en LATV Network\u2014, la serie Hunters y el documental 4TRO EL3MENTOS. Sus contenidos son emitidos en prime time en EE.UU. v\u00eda LATV y VOD, alcanzando m\u00e1s de 62 millones de hogares en mercados como Nueva York, Los \u00c1ngeles, Miami y Chicago. Equal Media ha estado presente con cobertura original y branded content en eventos como el Media Hub de los Latin Grammys, LAMC (NY), BIME (Bilbao, Bogot\u00e1), Vive Latino (CDMX), MIM LATAM, CAMM, entre otros hubs de la industria. Aliada de plataformas como Keychange, Femnoise, We Make Noise y la Municipalidad de Quilicura (Chile), Equal Media promueve una industria m\u00e1s equitativa, programando de forma activa proyectos liderados por mujeres, comunidades LGBTQ+ y sectores vulnerables. Bajo la direcci\u00f3n de Ulises Sanher \u2014reconocido por la UNAM y otras instituciones acad\u00e9micas por su labor cultural\u2014, Equal Media ha contribuido a formar nuevas audiencias desde la educaci\u00f3n, el activismo y la creatividad. Sanher ha sido invitado como speaker en foros como Circulart (COL), FIMPRO (MEX), Canadian Music Week (CAN), FME (CAN), SIM S\u00e3o Paulo (BR), MUPA (PAN), Corriente (PER) y Brasil Trends Conference. Tambi\u00e9n ha sido jurado externo de los Premios Rolling Stone en Espa\u00f1ol en Miami y ha ofrecido asesor\u00eda creativa en colaboraci\u00f3n con Berklee Valencia y la Asociaci\u00f3n de Supervisores Musicales.","sameAs":["https:\/\/www.equalmedia.mx\/","https:\/\/www.instagram.com\/equal.music","https:\/\/www.linkedin.com\/in\/ulises-sanher\/","https:\/\/www.youtube.com\/@equalmusicworld"],"url":"https:\/\/www.equalmedia.mx\/site\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.equalmedia.mx\/site\/wp-json\/wp\/v2\/posts\/7398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.equalmedia.mx\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.equalmedia.mx\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.equalmedia.mx\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.equalmedia.mx\/site\/wp-json\/wp\/v2\/comments?post=7398"}],"version-history":[{"count":1,"href":"https:\/\/www.equalmedia.mx\/site\/wp-json\/wp\/v2\/posts\/7398\/revisions"}],"predecessor-version":[{"id":7401,"href":"https:\/\/www.equalmedia.mx\/site\/wp-json\/wp\/v2\/posts\/7398\/revisions\/7401"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.equalmedia.mx\/site\/wp-json\/wp\/v2\/media\/7399"}],"wp:attachment":[{"href":"https:\/\/www.equalmedia.mx\/site\/wp-json\/wp\/v2\/media?parent=7398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.equalmedia.mx\/site\/wp-json\/wp\/v2\/categories?post=7398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.equalmedia.mx\/site\/wp-json\/wp\/v2\/tags?post=7398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}